{"id":1072739,"date":"2023-09-30T15:53:39","date_gmt":"2023-09-30T15:53:39","guid":{"rendered":"https:\/\/acrylgiessen.com\/sobre-nosotros\/megan-van-schoor-redactora-de-contenidos\/"},"modified":"2023-10-06T06:06:18","modified_gmt":"2023-10-06T06:06:18","slug":"megan-van-schoor","status":"publish","type":"page","link":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/","title":{"rendered":"Megan van Schoor \u2013 Redactora de Contenidos"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" data-services=\"facebook%7Cpinterest\" data-url=\"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/\" data-timestamp=\"1696572378\" data-hidezero=\"1\" data-backendurl=\"https:\/\/acrylgiessen.com\/es\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-color orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Facrylgiessen.com%2Fes%2Fsobre-nosotros%2Fmegan-van-schoor%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<span data-service=\"facebook\" style=\"color:#3b5998\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Facrylgiessen.com%2Fes%2Fsobre-nosotros%2Fmegan-van-schoor%2F&media=https%3A%2F%2Facrylgiessen.com%2Fwp-content%2Fuploads%2F2023%2F09%2Fmegan-van-schoor-1.png&description=Megan%20van%20Schoor%20%E2%80%93%20Redactora%20de%20Contenidos\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span class=\"shariff-text\">merken<\/span>&nbsp;<span data-service=\"pinterest\" style=\"color:#cb2027\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Facrylgiessen.com%2Fes%2Fsobre-nosotros%2Fmegan-van-schoor%2F&text=Megan%20van%20Schoor%20%E2%80%93%20Redactora%20de%20Contenidos\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><\/ul><\/div><p>&nbsp;<\/p>\n<h2>Antecedentes y Experiencia<\/h2>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1072716 alignleft\" src=\"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png\" alt=\"megan van schoor\" width=\"200\" height=\"202\" srcset=\"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png 400w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-298x300.png 298w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-30x30.png 30w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-75x75.png 75w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-110x110.png 110w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-50x50.png 50w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-100x100.png 100w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-96x96.png 96w, https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1-150x151.png 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Megan es escritora e investigadora licenciada en Ciencias Sociales por la Universidad de Ciudad del Cabo, especializada en Psicolog\u00eda y Ciencias Ambientales. Su pasi\u00f3n por el conocimiento y por dejar un impacto positivo ha impulsado su trabajo actual en el crecimiento consciente y sostenible en el sur de \u00c1frica. El amor de Megan por la naturaleza tambi\u00e9n la ha llevado a formarse como especialista en comportamiento animal. Trabaja a tiempo parcial adiestrando y rehabilitando perros. A Megan le interesan los efectos f\u00edsicos y psicol\u00f3gicos de los colores de nuestro entorno sobre nuestro estado de \u00e1nimo y bienestar. Adem\u00e1s, le preocupa c\u00f3mo el arte y la creatividad han sido parte integrante de la sociedad humana.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>El Papel de Megan en acrylgiessen<\/h2>\n<p>Megan van Schoor escribe entradas de blog sobre pintura, dibujo y teor\u00eda del color para acrylgiessen desde 2022.<\/p>\n<p>&nbsp;<\/p>\n<h2>Educaci\u00f3n<\/h2>\n<ul>\n<li>2020 \u2013 2023, Licenciatura en Ciencias Sociales con especializaci\u00f3n en Psicolog\u00eda y Ciencias Ambientales, en la <a href=\"https:\/\/uct.ac.za\/\" target=\"_blank\" rel=\"nofollow noopener\"><strong>University of Cape Town<\/strong><\/a><\/li>\n<li>2015 \u2013 2016, Comportamiento animal especializado en adiestramiento y rehabilitaci\u00f3n de perros, gatos y caballos, <strong><a href=\"https:\/\/www.ethology.co.za\/jm\/\" target=\"_blank\" rel=\"nofollow noopener\">Ethology Academy, Johannesburg<\/a><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Experiencia Laboral<\/h2>\n<ul>\n<li>2 a\u00f1os de experiencia en redacci\u00f3n sobre temas de pintura y artesan\u00eda<\/li>\n<li>2 a\u00f1os de experiencia en gesti\u00f3n de personas y comunicaci\u00f3n<\/li>\n<li>2 a\u00f1os de experiencia como Asesor de Cuidado de Animales de Compa\u00f1\u00eda<\/li>\n<li>8 a\u00f1os de experiencia como Aut\u00f3nomo en Comportamiento Animal<\/li>\n<li>10 a\u00f1os de experiencia como tutora de Matem\u00e1ticas<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>En los medios de comunicaci\u00f3n<\/h2>\n<ul>\n<li><strong><a id=\"ctl06_ctl04_lnkTitle\" href=\"https:\/\/www.absolutepets.com\/blog\/post\/2019\/03\/11\/everything-you-need-to-know-about-bonding-with-your-pet\" target=\"_blank\" rel=\"nofollow noopener\">Bonding with your pet \u2013 in 5 ways!<\/a><\/strong>, Absolute Pets Magazine, Marzo de 2019<\/li>\n<li>Megan tambi\u00e9n crea contenidos para otras marcas de Faessler Media Ltd, como <a href=\"https:\/\/artfilemagazine.com\/author\/megan-van-schoor\/\"><strong>artfilemagazine<\/strong><\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Los Favoritos de los Lectores por Megan<\/h2>\n<ul>\n<li><a href=\"https:\/\/acrylgiessen.com\/es\/signos-y-colores-zodiacales\/\"><strong>Colores zodiacales<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/acrylgiessen.com\/es\/colores-terciarios\/\"><strong>Colores terciarios<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/acrylgiessen.com\/es\/circulo-cromatico\/\"><strong>Circulo Cromatico<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/acrylgiessen.com\/es\/ideas-para-dibujar\/\"><strong>Ideas para Dibujar<\/strong><\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/acrylgiessen.com\/es\/author\/megan-van-schoor\"><strong>Todas las entradas de Megan van Schoor<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>Contacta con Megan<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.facebook.com\/profile.php?id=100006317887081\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Facebook<\/strong><\/a><\/li>\n<li><strong><a href=\"mailto:megan.vanschoor@acrylgiessen.com\" target=\"_blank\" rel=\"noopener\">eMail<\/a><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>acrylgiessen es tu revista creativa con muchos art\u00edculos sobre pintura, dibujo, manualidades y arte en general. M\u00e1s informaci\u00f3n <a href=\"https:\/\/acrylgiessen.com\/en\/about-us\"><strong>sobre nosotros<\/strong><\/a>.<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Antecedentes y Experiencia &nbsp; Megan es escritora e investigadora licenciada en Ciencias Sociales por la Universidad de Ciudad del Cabo, especializada en Psicolog\u00eda y Ciencias Ambientales. Su pasi\u00f3n por el conocimiento y por dejar un impacto positivo ha impulsado su trabajo actual en el crecimiento consciente y sostenible en el sur de \u00c1frica. El&#8230;<\/p>\n","protected":false},"author":2041,"featured_media":0,"parent":21085,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"default","_kad_post_title":"default","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-1072739","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Megan van Schoor \u2013 Redactora de Contenidos<\/title>\n<meta name=\"description\" content=\"Megan van Schoor es redactora de contenidos y cient\u00edfica social. Escribe art\u00edculos sobre pintura y teor\u00eda del color para acrylgiessen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Megan van Schoor \u2013 Redactora de Contenidos\" \/>\n<meta property=\"og:description\" content=\"Megan van Schoor es redactora de contenidos y cient\u00edfica social. Escribe art\u00edculos sobre pintura y teor\u00eda del color para acrylgiessen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/\" \/>\n<meta property=\"og:site_name\" content=\"acrylgiessen.com \u2013 Creative Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/acrylgiessen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T06:06:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@acrylgiessencom\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/\",\"url\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/\",\"name\":\"Megan van Schoor \u2013 Redactora de Contenidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acrylgiessen.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/megan-van-schoor-1.png\",\"datePublished\":\"2023-09-30T15:53:39+00:00\",\"dateModified\":\"2023-10-06T06:06:18+00:00\",\"description\":\"Megan van Schoor es redactora de contenidos y cient\u00edfica social. Escribe art\u00edculos sobre pintura y teor\u00eda del color para acrylgiessen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acrylgiessen.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/megan-van-schoor-1.png\",\"contentUrl\":\"https:\\\/\\\/acrylgiessen.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/megan-van-schoor-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/megan-van-schoor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre nosotros\",\"item\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/sobre-nosotros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Megan van Schoor \u2013 Redactora de Contenidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/\",\"name\":\"acrylgiessen.com \u2013 Creative Magazine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/#organization\",\"name\":\"acrylgiessen\",\"url\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/acrylgiessen.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/favicon_acrylgiessen_kadence.jpg\",\"contentUrl\":\"https:\\\/\\\/acrylgiessen.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/favicon_acrylgiessen_kadence.jpg\",\"width\":880,\"height\":880,\"caption\":\"acrylgiessen\"},\"image\":{\"@id\":\"https:\\\/\\\/acrylgiessen.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/acrylgiessen\\\/\",\"https:\\\/\\\/x.com\\\/acrylgiessencom\",\"https:\\\/\\\/www.instagram.com\\\/acrylgiessen\\\/\",\"https:\\\/\\\/www.pinterest.ch\\\/acrylgiessencom\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/acrylgiessencom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Megan van Schoor \u2013 Redactora de Contenidos","description":"Megan van Schoor es redactora de contenidos y cient\u00edfica social. Escribe art\u00edculos sobre pintura y teor\u00eda del color para acrylgiessen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/","og_locale":"es_ES","og_type":"article","og_title":"Megan van Schoor \u2013 Redactora de Contenidos","og_description":"Megan van Schoor es redactora de contenidos y cient\u00edfica social. Escribe art\u00edculos sobre pintura y teor\u00eda del color para acrylgiessen.","og_url":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/","og_site_name":"acrylgiessen.com \u2013 Creative Magazine","article_publisher":"https:\/\/www.facebook.com\/acrylgiessen\/","article_modified_time":"2023-10-06T06:06:18+00:00","og_image":[{"url":"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@acrylgiessencom","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/","url":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/","name":"Megan van Schoor \u2013 Redactora de Contenidos","isPartOf":{"@id":"https:\/\/acrylgiessen.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/#primaryimage"},"image":{"@id":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/#primaryimage"},"thumbnailUrl":"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png","datePublished":"2023-09-30T15:53:39+00:00","dateModified":"2023-10-06T06:06:18+00:00","description":"Megan van Schoor es redactora de contenidos y cient\u00edfica social. Escribe art\u00edculos sobre pintura y teor\u00eda del color para acrylgiessen.","breadcrumb":{"@id":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/#primaryimage","url":"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png","contentUrl":"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2023\/09\/megan-van-schoor-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/megan-van-schoor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/acrylgiessen.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sobre nosotros","item":"https:\/\/acrylgiessen.com\/es\/sobre-nosotros\/"},{"@type":"ListItem","position":3,"name":"Megan van Schoor \u2013 Redactora de Contenidos"}]},{"@type":"WebSite","@id":"https:\/\/acrylgiessen.com\/es\/#website","url":"https:\/\/acrylgiessen.com\/es\/","name":"acrylgiessen.com \u2013 Creative Magazine","description":"","publisher":{"@id":"https:\/\/acrylgiessen.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acrylgiessen.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acrylgiessen.com\/es\/#organization","name":"acrylgiessen","url":"https:\/\/acrylgiessen.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acrylgiessen.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2021\/06\/favicon_acrylgiessen_kadence.jpg","contentUrl":"https:\/\/acrylgiessen.com\/wp-content\/uploads\/2021\/06\/favicon_acrylgiessen_kadence.jpg","width":880,"height":880,"caption":"acrylgiessen"},"image":{"@id":"https:\/\/acrylgiessen.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/acrylgiessen\/","https:\/\/x.com\/acrylgiessencom","https:\/\/www.instagram.com\/acrylgiessen\/","https:\/\/www.pinterest.ch\/acrylgiessencom\/","https:\/\/www.youtube.com\/c\/acrylgiessencom"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"acrylgiessen","author_link":"https:\/\/acrylgiessen.com\/es\/author\/acrylgiessen\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/pages\/1072739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/users\/2041"}],"replies":[{"embeddable":true,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/comments?post=1072739"}],"version-history":[{"count":6,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/pages\/1072739\/revisions"}],"predecessor-version":[{"id":1072912,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/pages\/1072739\/revisions\/1072912"}],"up":[{"embeddable":true,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/pages\/21085"}],"wp:attachment":[{"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/media?parent=1072739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/categories?post=1072739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acrylgiessen.com\/es\/wp-json\/wp\/v2\/tags?post=1072739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}